{"id":5300,"date":"2026-04-15T14:56:32","date_gmt":"2026-04-15T14:56:32","guid":{"rendered":"https:\/\/costiproject.dannbust.com\/?page_id=5300"},"modified":"2026-04-15T15:03:09","modified_gmt":"2026-04-15T15:03:09","slug":"privacidad","status":"publish","type":"page","link":"http:\/\/costiproject.dannbust.com\/es\/privacidad\/","title":{"rendered":"Pol\u00edtica de privacidad"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"5300\" class=\"elementor elementor-5300\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-644e166 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"644e166\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"aux-parallax-section elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-19e4d0c\" data-id=\"19e4d0c\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-70c2915 elementor-widget elementor-widget-heading\" data-id=\"70c2915\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">pol\u00edtica de privacidad<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-30721a0 elementor-widget elementor-widget-text-editor\" data-id=\"30721a0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"mb-40\">En cumplimiento de la Ley 34\/2002, de 11 de julio, de Servicios de la Sociedad de la Informaci\u00f3n y Comercio Electr\u00f3nico (LSSI-CE), METZINERES SCCL informa que es titular del sitio web www.metzineres.org. De acuerdo con la exigencia del art\u00edculo 10 de la citada Ley, METZINERES informa de los siguientes datos: El titular de este sitio web es METZINERES, con CIF F01951714 y domicilio social en JOAQUIM COSTA, 3, 4-1 , 08001, BARCELONA, inscrita en el n\u00famero 15559 del Registro General de Cooperativas de Catalu\u00f1a. La direcci\u00f3n de correo electr\u00f3nico para contactar con la empresa es: metzineres@costiproject.dannbust.com.<\/p><h3>Usuario y r\u00e9gimen de responsabilidad<\/h3><p>La navegaci\u00f3n, acceso y uso por el sitio web METZINERES confiere la condici\u00f3n de usuario, por la que se aceptan todas las condiciones de uso aqu\u00ed establecidas, desde la navegaci\u00f3n por la p\u00e1gina web de METZINERES, sin perjuicio de la aplicaci\u00f3n de la correspondiente normativa de obligado cumplimiento legal seg\u00fan el caso.<\/p><p>El sitio web METZINERES proporciona un amplio abanico de informaci\u00f3n, servicios y datos. El usuario asume la responsabilidad del correcto uso del sitio web. Esta responsabilidad se extender\u00e1 a:<\/p><p>\u2022 La veracidad y licitud de la informaci\u00f3n facilitada por el usuario en los formularios extendidos por METZINERES para el acceso a determinados contenidos o servicios ofrecidos por el sitio web. El usuario ser\u00e1 el \u00fanico responsable de cualquier perjuicio, directo o indirecto, que pudiera ocasionar a cualquier persona a causa de la cumplimentaci\u00f3n del formulario con datos falsos, inexactos, incompletos, no actualizados o relativos a otra persona.<\/p><p>\u2022 El uso de la informaci\u00f3n, servicios y datos ofrecidos por METZINERES contrariamente a lo dispuesto en estas condiciones, la Ley, la moral, las buenas costumbres o el orden p\u00fablico, o que de cualquier otra forma puedan suponer lesi\u00f3n de los derechos de terceros o del mismo funcionamiento del sitio web.<\/p><h3>Pol\u00edtica de enlaces y exenciones de responsabilidad<\/h3><p>METZINERES no se hace responsable del contenido de los sitios web a los que el usuario pueda acceder a trav\u00e9s de los enlaces establecidos en su sitio web y declara que en ning\u00fan caso proceder\u00e1 a examinar o ejercer ning\u00fan tipo de control sobre el contenido de otros sitios de la red. Asimismo, no garantizar\u00e1 la disponibilidad t\u00e9cnica, exactitud, veracidad, validez o legalidad de sitios ajenos a su propiedad a los que se pueda acceder a trav\u00e9s de los enlaces.<\/p><p>METZINERES declara que ha adoptado todas las medidas necesarias para evitar cualquier da\u00f1o a los usuarios de su sitio web, que pudieran derivarse de la navegaci\u00f3n por su sitio web. En consecuencia, METZINERES no se hace responsable, en ning\u00fan caso, de los da\u00f1os y perjuicios que pueda sufrir el usuario por la navegaci\u00f3n por Internet.<\/p><h3>Modificaciones<\/h3><p>METZINERES se reserva el derecho de efectuar las modificaciones que considere oportunas, sin previo aviso, al contenido de su sitio web. Tanto en lo que se refiere a los contenidos del sitio web, como en las condiciones de uso del mismo. Estas modificaciones podr\u00e1n realizarse a trav\u00e9s de su sitio web por cualquier forma admisible en derecho y ser\u00e1n de obligado cumplimiento durante el tiempo en que se encuentren publicadas en el sitio web y hasta que no sean modificadas v\u00e1lidamente por otras posteriores.<\/p><h3>Protecci\u00f3n de datos<\/h3><p>METZINERES se compromete a asegurar que su informaci\u00f3n personal est\u00e9 protegida y no se utilice indebidamente.<\/p><p>Este documento explica qui\u00e9n es el responsable de tratamiento, con qu\u00e9 finalidad se tratar\u00e1 su informaci\u00f3n personal, la legitimaci\u00f3n para el tratamiento, c\u00f3mo la recopilamos, por qu\u00e9 la recopilamos as\u00ed como los derechos que le asisten.<\/p><p>Al facilitarnos su informaci\u00f3n personal y utilizar nuestro sitio web entendemos que ha le\u00eddo y comprendido los t\u00e9rminos relacionados con la informaci\u00f3n personal de protecci\u00f3n de datos de car\u00e1cter personal que a continuaci\u00f3n se exponen. METZINERES es responsable de cumplir con la legislaci\u00f3n vigente en materia de protecci\u00f3n de datos tanto nacional como europea y que tienen el objetivo de tratar sus datos de forma l\u00edcita, leal y transparente.<\/p><h4>1. \u00bfQui\u00e9n es el Responsable de Tratamiento?<\/h4><p>METZINERES, SCCL con CIF F01951714 y domicilio social situado en JOAQUIM COSTA, 3, 4-1, 08001, BARCELONA con perfil de Twitter @Metzineres_org y web www.metzineres.org.<\/p><p>Correo: protecciodedades@costiproject.dannbust.com<\/p><h4>2. Datos objeto de tratamiento<\/h4><p><b>a. Donaciones<\/b>: Cuando realiza una donaci\u00f3n recopilamos los datos necesarios para la ejecuci\u00f3n de esta donaci\u00f3n. Los datos pueden incluir el nombre y apellidos, correo electr\u00f3nico y datos bancarios para ejecutar la donaci\u00f3n como los datos de su tarjeta de cr\u00e9dito o d\u00e9bito. Para la ejecuci\u00f3n de la donaci\u00f3n recopilamos los datos de pago que nos ha proporcionado, transfiriendo \u00fanicamente a nuestros proveedores de servicios de pago los datos necesarios para su tramitaci\u00f3n.<\/p><p><b>b. Contacto<\/b>: Cuando se pone en contacto con METZINERES, bien por qu\u00e9 quiere estar informado de nuestras actividades bien por que quiere realizar cualquier otro tipo de contacto, a trav\u00e9s de esta web recopilamos sus datos de contacto como el nombre y apellido, n\u00famero de tel\u00e9fono y direcci\u00f3n de correo electr\u00f3nico.<\/p><h4>3. Finalidades de tratamiento<\/h4><p>Sus datos nos sirven para atender las siguientes finalidades, cuya legitimidad respectiva es:<\/p><p><b>a. Cumplimiento de un contrato<\/b>: Se tratan los datos necesarios para el cumplimiento y la gesti\u00f3n de las donaciones efectuadas.<\/p><p><b>b. Consentimiento expreso<\/b>: Para poder tratar sus datos es necesario que nos d\u00e9 su consentimiento, mediante el cual acepta que sus datos sean tratados para una finalidad determinada como el env\u00edo peri\u00f3dico de las noticias e informaci\u00f3n sobre nuestra Organizaci\u00f3n.<\/p><p><b>c. Cumplimiento de obligaciones legales<\/b>: Se trata de tratamientos que nos exige la ley y que no podemos incumplir como por ejemplo: colaboraci\u00f3n con los jueces y tribunales; colaboraci\u00f3n con la Autoridad de Protecci\u00f3n de Datos correspondiente; cumplimiento de obligaciones tributarias y colaboraci\u00f3n con la Agencia Estatal de la Administraci\u00f3n Tributaria; colaboraci\u00f3n con las fuerzas y cuerpos del Estado.<\/p><p><b>d. Inter\u00e9s leg\u00edtimo<\/b>: En todo caso, le informamos que hemos llevado a cabo una reflexi\u00f3n minuciosa sobre el valor del inter\u00e9s leg\u00edtimo que nos ampara en estos tratamientos de datos y la eventual existencia de alg\u00fan perjuicio o inter\u00e9s contrario suyo, adem\u00e1s de asegurarnos de que la informaci\u00f3n que destinemos a realizar este estudio no sufra ning\u00fan riesgo de seguridad. Son tratamientos que queremos llevar a cabo si usted no se opone para la comunicaci\u00f3n de aspectos que consideramos importantes y que no se consideren env\u00edo de noticias (por ejemplo, cambios en el evento organizados por METZINERES, etc.).<\/p><h4>4. \u00bfA qui\u00e9n podemos comunicar su informaci\u00f3n personal?<\/h4><p>En algunos casos, es necesario que comuniquemos la informaci\u00f3n que nos ha proporcionado a empresas que nos presten servicios de tecnolog\u00eda de la informaci\u00f3n, servicios de seguridad, servicios financieros, etc. Estas empresas \u00fanicamente tienen acceso a la informaci\u00f3n personal que necesitan para llevar a cabo estos servicios y se les exige que mantengan la confidencialidad de sus datos y no pueden utilizarla de otra forma que aqu\u00e9lla que los hemos solicitado. En todos los casos, METZINERES asume la responsabilidad por la informaci\u00f3n personal que nos facilite y solicitamos a aquellos proveedores con los que compartimos sus datos que apliquen el mismo grado de protecci\u00f3n de la informaci\u00f3n que nosotros.<\/p><h4>5. \u00bfCu\u00e1nto tiempo almacenamos sus datos?<\/h4><p>S\u00f3lo almacenamos su informaci\u00f3n personal en la medida en que la necesitamos a fin de poder utilizarla seg\u00fan la finalidad por la que fue recabada, y seg\u00fan la base jur\u00eddica del tratamiento de la misma de conformidad con la ley aplicable. Mantendremos su informaci\u00f3n persona para ejecutar la donaci\u00f3n o mientras usted no ejerza su derecho de supresi\u00f3n o limitaci\u00f3n del tratamiento de sus datos. En estos casos, mantendremos la informaci\u00f3n debidamente bloqueada, sin darle ning\u00fan uso, mientras pueda ser necesaria para el ejercicio o defensa de reclamaciones o pueda derivarse alg\u00fan tipo de responsabilidad judicial, legal o contractual de su tratamiento, que haya ser atendida y para ello sea necesaria su recuperaci\u00f3n.<\/p><h4>6. \u00bfC\u00f3mo puede ejercer sus derechos?<\/h4><p>Puede ejercer sus derechos de acceso, rectificaci\u00f3n, supresi\u00f3n, limitaci\u00f3n, oposici\u00f3n, portabilidad o revocar su consentimiento adjuntando copia de su DNI o documento acreditativo de su identidad a trav\u00e9s del correo protecciodedades@costiproject.dannbust.com.<\/p><p>En caso de que lo considere necesario puede interponer una reclamaci\u00f3n a la Agencia Espa\u00f1ola de Protecci\u00f3n de Datos (www.aepd.es).<\/p><h4>7. Seguridad de la informaci\u00f3n<\/h4><p>METZINERES ha tomado todas las medidas legalmente requeridas para la protecci\u00f3n de datos personales; asimismo, ha adoptado todos los dispositivos t\u00e9cnicos a su alcance para evitar la p\u00e9rdida, mal uso, alteraci\u00f3n, acceso o robo de los datos personales facilitados por los usuarios de la web. El usuario tendr\u00e1 en cuenta, sin embargo, que las medidas de seguridad en Internet no son absolutamente inviolables.<\/p><h3>Propiedad intelectual e industrial<\/h3><p>METZINERES por s\u00ed mismo o como cesionario, es titular de todos los derechos de propiedad intelectual e industrial de su sitio web, as\u00ed como de los elementos contenidos en la misma (a t\u00edtulo enunciativo, im\u00e1genes, sonido, audio, v\u00eddeo, software o textos, marcas o logotipos, combinaciones de colores, estructura y dise\u00f1o, selecci\u00f3n de materiales utilizados, programas inform\u00e1ticos necesarios para su funcionamiento). Por tanto, ser\u00e1n obras protegidas como propiedad intelectual por el ordenamiento jur\u00eddico espa\u00f1ol, siendo aplicables tanto la legislaci\u00f3n espa\u00f1ola y comunitaria en este campo, como los tratados internacionales relativos a la materia y suscritos por Espa\u00f1a. Todos los derechos reservados. De conformidad con lo que establece la Ley de Propiedad Intelectual, queda expresamente prohibida la reproducci\u00f3n, distribuci\u00f3n y comunicaci\u00f3n p\u00fablica, incluida su modalidad de poner a disposici\u00f3n, la totalidad o parte de los contenidos de este sitio web, con fines comerciales, en cualquier soporte y por cualquier medio t\u00e9cnico, sin la autorizaci\u00f3n de METZINERES.<\/p><p>L\u2019usuari es compromet a respectar els drets de propietat intel\u00b7lectual i industrial titularitat de METZINERES. Podr\u00e0 visualitzar els elements del portal i fins i tot imprimir-los, copiar-los i emmagatzemar-los en el disc dur del seu ordinador o en qualsevol altre suport f\u00edsic sempre que sigui, \u00fanica i exclusivament, per al seu \u00fas personal i privat. L\u2019usuari haur\u00e0 d\u2019abstenir-se de suprimir, alterar, eludir o manipular qualsevol dispositiu de protecci\u00f3 o sistema de seguretat que estigu\u00e9s instal\u00b7lat a les p\u00e0gines de METZINERES.<\/p><h3>Acciones legales, ley aplicable y jurisdicci\u00f3n<\/h3><p>METZINERES tambi\u00e9n se reserva el derecho de presentar las acciones civiles o penales que considere oportunas por el uso indebido de su sitio web y contenidos, o por el incumplimiento de las presentes condiciones. La relaci\u00f3n entre el usuario y el prestamista se regir\u00e1 por la normativa vigente y aplicable en territorio espa\u00f1ol. En caso de surgir cualquier controversia, las partes podr\u00e1n someter sus disputas a arbitraje o acudir a la jurisdicci\u00f3n ordinaria de acuerdo con las normas sobre jurisdicci\u00f3n y jurisdicci\u00f3n al respecto. METZINERES est\u00e1 domiciliada en BARCELONA, Espa\u00f1a.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>pol\u00edtica de privacidad En cumplimiento de la Ley 34\/2002, de 11 de julio, de Servicios de la Sociedad de la Informaci\u00f3n y Comercio Electr\u00f3nico (LSSI-CE), METZINERES SCCL informa que es titular del sitio web www.metzineres.org. De acuerdo con la exigencia del art\u00edculo 10 de la citada Ley, METZINERES informa de los siguientes datos: El titular [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-5300","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"http:\/\/costiproject.dannbust.com\/es\/wp-json\/wp\/v2\/pages\/5300","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/costiproject.dannbust.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"http:\/\/costiproject.dannbust.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"http:\/\/costiproject.dannbust.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/costiproject.dannbust.com\/es\/wp-json\/wp\/v2\/comments?post=5300"}],"version-history":[{"count":10,"href":"http:\/\/costiproject.dannbust.com\/es\/wp-json\/wp\/v2\/pages\/5300\/revisions"}],"predecessor-version":[{"id":5310,"href":"http:\/\/costiproject.dannbust.com\/es\/wp-json\/wp\/v2\/pages\/5300\/revisions\/5310"}],"wp:attachment":[{"href":"http:\/\/costiproject.dannbust.com\/es\/wp-json\/wp\/v2\/media?parent=5300"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}